{"id":43,"count":0,"description":"","link":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/","name":"Informa\u021bii generale despre cartea de identitate","slug":"informatii-generale-despre-cartea-de-identitate","taxonomy":"category","parent":5,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Arhive Informa\u021bii generale despre cartea de identitate - SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/\" \/>\r\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Arhive Informa\u021bii generale despre cartea de identitate - SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/\" \/>\r\n<meta property=\"og:site_name\" content=\"SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/index.php\\\/category\\\/evidenta-persoanei\\\/informatii-generale-despre-cartea-de-identitate\\\/\",\"url\":\"https:\\\/\\\/depslobozia.ro\\\/index.php\\\/category\\\/evidenta-persoanei\\\/informatii-generale-despre-cartea-de-identitate\\\/\",\"name\":\"Arhive Informa\u021bii generale despre cartea de identitate - SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/index.php\\\/category\\\/evidenta-persoanei\\\/informatii-generale-despre-cartea-de-identitate\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/index.php\\\/category\\\/evidenta-persoanei\\\/informatii-generale-despre-cartea-de-identitate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/depslobozia.ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eviden\u021ba Persoanei\",\"item\":\"https:\\\/\\\/depslobozia.ro\\\/index.php\\\/category\\\/evidenta-persoanei\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Informa\u021bii generale despre cartea de identitate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/#website\",\"url\":\"https:\\\/\\\/depslobozia.ro\\\/\",\"name\":\"DIREC\u0162IA DE EVIDEN\u0162A PERSOANELOR SLOBOZIA\",\"description\":\"Municipiul SLOBOZIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depslobozia.ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/#organization\",\"name\":\"Directia de Evidenta Persoanelor Slobozia\",\"url\":\"https:\\\/\\\/depslobozia.ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/depslobozia.ro\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/StemSlobozia.png\",\"contentUrl\":\"https:\\\/\\\/depslobozia.ro\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/StemSlobozia.png\",\"width\":68,\"height\":90,\"caption\":\"Directia de Evidenta Persoanelor Slobozia\"},\"image\":{\"@id\":\"https:\\\/\\\/depslobozia.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhive Informa\u021bii generale despre cartea de identitate - SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/","og_locale":"ro_RO","og_type":"article","og_title":"Arhive Informa\u021bii generale despre cartea de identitate - SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA","og_url":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/","og_site_name":"SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/","url":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/","name":"Arhive Informa\u021bii generale despre cartea de identitate - SERVICIUL PUBLIC COMUNITAR LOCAL DE EVIDEN\u0162A A PERSOANELOR SLOBOZIA","isPartOf":{"@id":"https:\/\/depslobozia.ro\/#website"},"breadcrumb":{"@id":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/#breadcrumb"},"inLanguage":"ro-RO"},{"@type":"BreadcrumbList","@id":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/informatii-generale-despre-cartea-de-identitate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/depslobozia.ro\/"},{"@type":"ListItem","position":2,"name":"Eviden\u021ba Persoanei","item":"https:\/\/depslobozia.ro\/index.php\/category\/evidenta-persoanei\/"},{"@type":"ListItem","position":3,"name":"Informa\u021bii generale despre cartea de identitate"}]},{"@type":"WebSite","@id":"https:\/\/depslobozia.ro\/#website","url":"https:\/\/depslobozia.ro\/","name":"DIREC\u0162IA DE EVIDEN\u0162A PERSOANELOR SLOBOZIA","description":"Municipiul SLOBOZIA","publisher":{"@id":"https:\/\/depslobozia.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depslobozia.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/depslobozia.ro\/#organization","name":"Directia de Evidenta Persoanelor Slobozia","url":"https:\/\/depslobozia.ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/depslobozia.ro\/#\/schema\/logo\/image\/","url":"https:\/\/depslobozia.ro\/wp-content\/uploads\/2021\/10\/StemSlobozia.png","contentUrl":"https:\/\/depslobozia.ro\/wp-content\/uploads\/2021\/10\/StemSlobozia.png","width":68,"height":90,"caption":"Directia de Evidenta Persoanelor Slobozia"},"image":{"@id":"https:\/\/depslobozia.ro\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/depslobozia.ro\/index.php\/wp-json\/wp\/v2\/categories\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depslobozia.ro\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/depslobozia.ro\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/depslobozia.ro\/index.php\/wp-json\/wp\/v2\/categories\/5"}],"wp:post_type":[{"href":"https:\/\/depslobozia.ro\/index.php\/wp-json\/wp\/v2\/posts?categories=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}